{"id":192,"date":"2024-01-14T20:22:58","date_gmt":"2024-01-14T19:22:58","guid":{"rendered":"https:\/\/www.joobwe.es\/?p=192"},"modified":"2024-03-22T11:25:40","modified_gmt":"2024-03-22T10:25:40","slug":"como-obtener-el-informe-de-vida-laboral","status":"publish","type":"post","link":"https:\/\/www.joobwe.es\/index.php\/2024\/01\/14\/como-obtener-el-informe-de-vida-laboral\/","title":{"rendered":"\u00bfC\u00f3mo obtener el Informe de Vida Laboral?"},"content":{"rendered":"<div class=\"sws_supernormalaction\"><button on=\"tap:superwebshare-lightbox\" class=\"superwebshare_normal_button1 superwebshare-button-medium superwebshare-button-default superwebshare_prompt superwebshare_button_svg\" style=\"color:#ffffff;background-color: #000000;\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"superwebshare-svg\"  fill=\"currentColor\" viewBox=\"0 0 1000 1000\" stroke=\"currentColor\" stroke-width=\"0\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M789.86,323.67c91.79,0,164.25-72.46,164.25-164.25S881.64,0,789.86,0S625.6,72.46,625.6,164.25c0,4.83,0,14.49,0,24.15L306.76,371.98c-24.15-24.15-57.97-33.82-96.62-33.82c-91.79,0-164.25,72.46-164.25,164.25s72.46,164.25,164.25,164.25c38.65,0,72.46-14.49,96.62-33.82L625.6,821.26c0,9.66,0,14.49,0,19.32c0,86.96,72.46,159.42,159.42,159.42s159.42-72.46,159.42-159.42s-67.63-159.42-154.59-159.42c-33.82,0-67.63,9.66-96.62,33.82L374.4,526.57c0-9.66,0-19.32,0-24.15s0-14.49,0-24.15l318.84-188.41C717.39,314.01,751.21,323.67,789.86,323.67z\" \/><\/svg><span>@<\/span><\/button><\/div>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Informe de Vida Laboral: qu\u00e9 es y c\u00f3mo solicitarlo\" width=\"749\" height=\"421\" src=\"https:\/\/www.youtube.com\/embed\/W8kF8zwxpZk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>El <strong>Informe de Vida Laboral<\/strong> es un documento que refleja de manera cronol\u00f3gica todas las actividades profesionales de una persona, precisando las altas y bajas en cada empresa en las que haya trabajado o prestado servicios.<\/p>\n\n\n\n<p>Estos datos incluyen las cotizaciones acumuladas, que son las que permiten acceder a ciertas prestaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPara qu\u00e9 sirve un Informe de Vida Laboral?<\/h2>\n\n\n\n<p>Aunque el fin principal del <strong>Informe de Vida Laboral<\/strong> es obtener informaci\u00f3n respecto a nuestras cotizaciones en el sistema de la Seguridad Social, su contenido puede ayudar a realizar m\u00e1s tr\u00e1mites.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prestaci\u00f3n por desempleo<\/strong><\/h3>\n\n\n\n<p>Al reflejar las cotizaciones, la Vida Laboral permite confirmar la relaci\u00f3n que ha tenido una persona con todas las empresas, de manera cronol\u00f3gica y el detalle respecto a las fechas exactas de alta y baja, como tambi\u00e9n la modalidad de trabajo, si ha sido a jornada parcial o a tiempo completo.<\/p>\n\n\n\n<p>Este detalle es requerido por la Seguridad Social al momento de conceder una prestaci\u00f3n por desempleo y para calcular el monto que recibir\u00e1 la persona desempleada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prestaci\u00f3n por jubilaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Al igual que en la prestaci\u00f3n por desempleo, el Informe de Vida Laboral permite calcular el total de dinero que podr\u00e1 recibir una persona trabajadora durante su jubilaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prestaci\u00f3n por maternidad<\/strong><\/h3>\n\n\n\n<p>Para realizar la solicitud de prestaci\u00f3n por nacimiento y cuidado de menor se exige una cantidad de d\u00edas cotizados durante los \u00faltimos meses. Para poder demostrar que se cumple con este requisito es necesario contar con el Informe de Vida Laboral. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Qu\u00e9 es y c\u00f3mo obtener el Informe Vida Laboral\" width=\"749\" height=\"421\" src=\"https:\/\/www.youtube.com\/embed\/u1iXYKRGU2k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo obtener el Informe de Vida Laboral?<\/h2>\n\n\n\n<p>Es importante destacar que el Informe de Vida Laboral es un documento oficial y gratuito, por lo que podr\u00e1s solicitarlo todas las veces que los necesites sin ning\u00fan coste asociado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfD\u00f3nde y c\u00f3mo solicitar la vida laboral?<\/strong><\/h3>\n\n\n\n<p>El documento acreditativo de la historia profesional se debe solicitar en las oficinas de la <a href=\"https:\/\/portal.seg-social.gob.es\/wps\/portal\/importass\/importass\/Categorias\/Vida+laboral+e+informes\/Informes+sobre+tu+situacion+laboral\/Informe+de+tu+vida+laboral\" target=\"_blank\" rel=\"noreferrer noopener\">Seguridad Social<\/a>.<\/p>\n\n\n\n<p>La solicitud se puede realizar por mensajer\u00eda de texto (SMS), por tel\u00e9fono 901 50 20 50 o&nbsp;915410291, por internet, o a trav\u00e9s de la App Seguridad Social.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Descargar el Informe de Vida Laboral<\/h2>\n\n\n\n<p>Solicitar los documentos por Internet suele ser una de las formas m\u00e1s simples, aqu\u00ed te contamos los pasos a seguir:<\/p>\n\n\n\n<p>Ingresa a <a href=\"https:\/\/portal.seg-social.gob.es\/wps\/portal\/importass\/importass\/Categorias\/Vida+laboral+e+informes\/Informes+sobre+tu+situacion+laboral\/Informe+de+tu+vida+laboral\">Informe de tu vida laboral<\/a> en la web de la Seguridad Social<\/p>\n\n\n\n<p>Pincha en \u2018consultar vida laboral\u2019 y luego <strong>identif\u00edcate a trav\u00e9s de SMS<\/strong> o con algunos de los registros digitales si tienes alguno de ellos: Cl@ve permanente, Cl@ve PIN o DNIe o certificado.<\/p>\n\n\n\n<p>Luego de estos pasos ya podr\u00e1s ver tu informaci\u00f3n y descargarla pinchando el bot\u00f3n correspondiente.<\/p>\n\n\n\n<p><strong>Es importante revisar que toda la informaci\u00f3n sea correcta y si no es as\u00ed debes ponerte en contacto a trav\u00e9s de los n\u00fameros que aparezcan en pantalla y solucionarlo<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/jet-tickets.com\/?marker=243050\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"90\" src=\"https:\/\/www.joobwe.es\/wp-content\/uploads\/2024\/01\/2014-10-07_JetRadar_Airplane-green-valey_728-90.png\" alt=\"\" class=\"wp-image-178\" srcset=\"https:\/\/www.joobwe.es\/wp-content\/uploads\/2024\/01\/2014-10-07_JetRadar_Airplane-green-valey_728-90.png 728w, https:\/\/www.joobwe.es\/wp-content\/uploads\/2024\/01\/2014-10-07_JetRadar_Airplane-green-valey_728-90-300x37.png 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>@ El Informe de Vida Laboral es un documento que refleja de manera cronol\u00f3gica todas las actividades profesionales de una persona, precisando las altas y bajas en cada empresa en las que haya trabajado o prestado servicios. Estos datos incluyen las cotizaciones acumuladas, que son las que permiten acceder a ciertas prestaciones. \u00bfPara qu\u00e9 sirve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":194,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[113],"class_list":["post-192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-vida-laboral"],"_links":{"self":[{"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":3,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":1086,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/posts\/192\/revisions\/1086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/media\/194"}],"wp:attachment":[{"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joobwe.es\/index.php\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}